{"id":11083,"date":"2026-03-29T14:44:06","date_gmt":"2026-03-29T14:44:06","guid":{"rendered":"https:\/\/adcelectronique.com\/?post_type=product&#038;p=11083"},"modified":"2026-03-29T14:44:08","modified_gmt":"2026-03-29T14:44:08","slug":"clavier-eclipse-lcd32spr","status":"publish","type":"product","link":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/","title":{"rendered":"CLAVIER ECLIPSE LCD32SPR"},"content":{"rendered":"<h3>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0CLAVIER ECLIPSE LCD32SPR<\/h3>\n<h4><em>\u00a0\u00a0DESCRIPTION:<\/em><\/h4>\n<p>L&rsquo;Eclipse LCD32S est un clavier LCD dot\u00e9 d&rsquo;un affichage texte fournissant des informations d\u00e9taill\u00e9es sur les zones, les anomalies et le type d&rsquo;armement, ainsi que de touches sensibles. Il fait partie des syst\u00e8mes d&rsquo;alarme de la s\u00e9rie Eclipse.<\/p>\n<p>Ce clavier dispose d&rsquo;une entr\u00e9e zone et d&rsquo;une sortie PGM. L&rsquo;Eclipse LCD32S est adapt\u00e9 \u00e0 la programmation par les techniciens et \u00e0 la gestion quotidienne par l&rsquo;utilisateur de tous les panneaux de la s\u00e9rie Eclipse.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<h4><em>\u00a0\u00a0DESCRIPTION:<\/em><\/h4>\n<p>L&rsquo;Eclipse LCD32S est un clavier LCD dot\u00e9 d&rsquo;un affichage texte fournissant des informations d\u00e9taill\u00e9es sur les zones, les anomalies et le type d&rsquo;armement, ainsi que de touches sensibles. Il fait partie des syst\u00e8mes d&rsquo;alarme de la s\u00e9rie Eclipse.<\/p>\n<p>Ce clavier dispose d&rsquo;une entr\u00e9e zone et d&rsquo;une sortie PGM. L&rsquo;Eclipse LCD32S est adapt\u00e9 \u00e0 la programmation par les techniciens et \u00e0 la gestion quotidienne par l&rsquo;utilisateur de tous les panneaux de la s\u00e9rie Eclipse.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":11084,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[149],"product_cat":[147],"product_tag":[],"class_list":["post-11083","product","type-product","status-publish","has-post-thumbnail","product_brand-teletek","product_cat-anti-intrusion","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.2 (Yoast SEO v26.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CLAVIER ECLIPSE LCD32SPR - ADC Electronique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CLAVIER ECLIPSE LCD32SPR\" \/>\n<meta property=\"og:description\" content=\"\u00a0\u00a0DESCRIPTION: L&#039;Eclipse LCD32S est un clavier LCD dot\u00e9 d&#039;un affichage texte fournissant des informations d\u00e9taill\u00e9es sur les zones, les anomalies et le type d&#039;armement, ainsi que de touches sensibles. Il fait partie des syst\u00e8mes d&#039;alarme de la s\u00e9rie Eclipse.  Ce clavier dispose d&#039;une entr\u00e9e zone et d&#039;une sortie PGM. L&#039;Eclipse LCD32S est adapt\u00e9 \u00e0 la programmation par les techniciens et \u00e0 la gestion quotidienne par l&#039;utilisateur de tous les panneaux de la s\u00e9rie Eclipse.  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/\" \/>\n<meta property=\"og:site_name\" content=\"ADC Electronique\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-29T14:44:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/\",\"url\":\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/\",\"name\":\"CLAVIER ECLIPSE LCD32SPR - ADC Electronique\",\"isPartOf\":{\"@id\":\"https:\/\/adcelectronique.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-scaled.png\",\"datePublished\":\"2026-03-29T14:44:06+00:00\",\"dateModified\":\"2026-03-29T14:44:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#primaryimage\",\"url\":\"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-scaled.png\",\"contentUrl\":\"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-scaled.png\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/adcelectronique.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/adcelectronique.com\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CLAVIER ECLIPSE LCD32SPR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/adcelectronique.com\/#website\",\"url\":\"https:\/\/adcelectronique.com\/\",\"name\":\"ADC Electronique\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/adcelectronique.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CLAVIER ECLIPSE LCD32SPR - ADC Electronique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/","og_locale":"fr_FR","og_type":"article","og_title":"CLAVIER ECLIPSE LCD32SPR","og_description":"\u00a0\u00a0DESCRIPTION: L'Eclipse LCD32S est un clavier LCD dot\u00e9 d'un affichage texte fournissant des informations d\u00e9taill\u00e9es sur les zones, les anomalies et le type d'armement, ainsi que de touches sensibles. Il fait partie des syst\u00e8mes d'alarme de la s\u00e9rie Eclipse.  Ce clavier dispose d'une entr\u00e9e zone et d'une sortie PGM. L'Eclipse LCD32S est adapt\u00e9 \u00e0 la programmation par les techniciens et \u00e0 la gestion quotidienne par l'utilisateur de tous les panneaux de la s\u00e9rie Eclipse.  &nbsp;","og_url":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/","og_site_name":"ADC Electronique","article_modified_time":"2026-03-29T14:44:08+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-1024x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/","url":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/","name":"CLAVIER ECLIPSE LCD32SPR - ADC Electronique","isPartOf":{"@id":"https:\/\/adcelectronique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#primaryimage"},"image":{"@id":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#primaryimage"},"thumbnailUrl":"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-scaled.png","datePublished":"2026-03-29T14:44:06+00:00","dateModified":"2026-03-29T14:44:08+00:00","breadcrumb":{"@id":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#primaryimage","url":"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-scaled.png","contentUrl":"https:\/\/adcelectronique.com\/wp-content\/uploads\/2026\/03\/50-scaled.png","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/adcelectronique.com\/index.php\/product\/clavier-eclipse-lcd32spr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adcelectronique.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/adcelectronique.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"CLAVIER ECLIPSE LCD32SPR"}]},{"@type":"WebSite","@id":"https:\/\/adcelectronique.com\/#website","url":"https:\/\/adcelectronique.com\/","name":"ADC Electronique","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adcelectronique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/product\/11083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/comments?post=11083"}],"version-history":[{"count":0,"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/product\/11083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/media\/11084"}],"wp:attachment":[{"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/media?parent=11083"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=11083"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=11083"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adcelectronique.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=11083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}